{"id":10,"date":"2024-06-03T22:29:10","date_gmt":"2024-06-03T20:29:10","guid":{"rendered":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/?page_id=10"},"modified":"2024-06-08T18:31:05","modified_gmt":"2024-06-08T16:31:05","slug":"inicio","status":"publish","type":"page","link":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/","title":{"rendered":"Inicio"},"content":{"rendered":"\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:700px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-background-dim-0 has-background-dim\" style=\"background-color:#ba8888\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1463\" class=\"wp-block-cover__image-background wp-image-56\" alt=\"\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-scaled.jpg\" style=\"object-position:50% 0%\" data-object-fit=\"cover\" data-object-position=\"50% 0%\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-scaled.jpg 2560w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-300x171.jpg 300w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-1024x585.jpg 1024w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-768x439.jpg 768w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-1536x878.jpg 1536w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-2048x1170.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h1 class=\"wp-block-heading has-text-align-center has-text-color\" style=\"color:#121212\">Mezcla los colores<\/h1>\n\n\n\n<p class=\"has-text-align-center has-text-color wp-block-paragraph\" style=\"color:#121212;font-size:17px\"><\/p>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n<\/div><\/div>\n\n\n\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image is-resized icon-style is-style-default\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/rodillo-1.png\" alt=\"\" class=\"wp-image-57\"\/><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-neve-text-color-color has-text-color\">Servicio Garantizado<\/h3>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Gracias a la utilizaci\u00f3n de las mejores marcas del mercado y nuestro saber hacer podemos garantizar nuestros servicios.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image is-resized icon-style is-style-default\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/casa-1.png\" alt=\"\" class=\"wp-image-58\"\/><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-neve-text-color-color has-text-color\">Particulares<\/h3>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Atenci\u00f3n personalizada a particulares y comunidades de vecinos.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"128\" height=\"128\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/edificio.png\" alt=\"\" class=\"wp-image-59\" style=\"width:96px;height:auto\"\/><\/figure>\n<\/div>\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-neve-text-color-color has-text-color\">Industrial<\/h3>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\">Disponemos de un equipo con la m\u00e1xima experiencia en trabajos industriales.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:600px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-light-bg-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"782\" height=\"921\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/bote-pintura-1-1.png\" alt=\"\" class=\"wp-image-62\" style=\"width:516px;height:auto\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/bote-pintura-1-1.png 782w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/bote-pintura-1-1-255x300.png 255w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/bote-pintura-1-1-768x905.png 768w\" sizes=\"auto, (max-width: 782px) 100vw, 782px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-neve-text-color-color has-text-color\">Servicios que te encantan<\/h2>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"44\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/telefono.png\" alt=\"\" class=\"wp-image-63\" style=\"width:51px;height:auto\"\/><\/figure>\n<\/div>\n\n\n<pre class=\"wp-block-code has-neve-text-color-color has-text-color\" style=\"font-size:31px\"><code> <strong>647447169 \/ 650959568<\/strong><\/code><\/pre>\n\n\n\n<p class=\"has-text-align-center has-x-large-font-size wp-block-paragraph\" style=\"padding-top:0;padding-right:0;padding-bottom:0;padding-left:0\">\u00a1 <strong>LLAMANOS !<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:600px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<h2 class=\"wp-block-heading has-text-align-left has-neve-text-color-color has-text-color\">Marcas que trabajamos<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En <strong>Pinturas Perez Torres<\/strong>, seleccionamos cuidadosamente las marcas que utilizamos para garantizar la calidad y durabilidad de nuestros trabajos. Optamos por productos de reconocidas empresas l\u00edderes en la industria, cuyas pinturas y utensilios han sido probados y aprobados por su resistencia y rendimiento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nuestro compromiso con estas marcas se debe a su constante innovaci\u00f3n y su dedicaci\u00f3n a la satisfacci\u00f3n del cliente. Al trabajar con ellas, aseguramos que cada proyecto sea realizado con los materiales m\u00e1s avanzados y confiables disponibles en el mercado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por eso, cuando eliges <strong>Pinturas Perez Torres<\/strong>, est\u00e1s eligiendo la confianza en cada brocha que aplicamos y en cada color que seleccionamos para tu hogar o negocio.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"578\" height=\"577\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/conjunto-de-marcas.png\" alt=\"\" class=\"wp-image-64\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/conjunto-de-marcas.png 578w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/conjunto-de-marcas-300x300.png 300w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/conjunto-de-marcas-150x150.png 150w\" sizes=\"auto, (max-width: 578px) 100vw, 578px\" \/><\/figure>\n<\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:700px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-dark-bg-background-color has-background-dim\"><\/span><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"500\" class=\"wp-block-cover__image-background wp-image-65\" alt=\"\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/row-background-image-2-1024x543-1000x500-1.png\" data-object-fit=\"cover\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/row-background-image-2-1024x543-1000x500-1.png 1000w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/row-background-image-2-1024x543-1000x500-1-300x150.png 300w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/row-background-image-2-1024x543-1000x500-1-768x384.png 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:80px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-left has-nv-text-dark-bg-color has-text-color\">\u00bfA qui\u00e9n nos dirigimos principalmente?<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Entre nuestros clientes contamos con gran cantidad de empresas de diversos sectores. Desde centros oficiales, ayuntamientos, colegios , polideportivos, empresas de construcci\u00f3n, hosteler\u00eda, comercio, arquitectos y decoradores, comunidades, Administradores de Fincas y particulares.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"500\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/compromiso.png\" alt=\"\" class=\"wp-image-67\" style=\"width:119px;height:auto\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/compromiso.png 500w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/compromiso-300x300.png 300w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/compromiso-150x150.png 150w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Compromiso Ecol\u00f3gico<\/figcaption><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"100\" height=\"100\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/equipo-profesional.png\" alt=\"\" class=\"wp-image-66\" style=\"width:116px;height:auto\"\/><figcaption class=\"wp-element-caption\">Equipo Profesional<\/figcaption><\/figure>\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:50%\"><\/div>\n<\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:600px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-site-bg-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-neve-text-color-color has-text-color\">Servicios<\/h2>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"389\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/obranueva-1.png\" alt=\"\" class=\"wp-image-71\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/obranueva-1.png 420w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/obranueva-1-300x278.png 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><figcaption class=\"wp-element-caption\"><strong>Obra nueva<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Participamos en obras de nueva edificaci\u00f3n (viviendas, garajes, pabellones, polideportivos, \u2026)<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Disponemos de equipos de proyecci\u00f3n (airless y airmix con mangueras calefactables, calderines de gota, turbinas, maquinas de chorreo<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"389\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/altadecoracion-1.png\" alt=\"\" class=\"wp-image-72\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/altadecoracion-1.png 420w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/altadecoracion-1-300x278.png 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><figcaption class=\"wp-element-caption\"><strong>Alta decoraci\u00f3n<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Especialidades: lisos, espatulados, trapeados, diferentes estucos, murales, envejecidos, p\u00e1tinas, estarcidos, barnizados, imitaci\u00f3n a m\u00e1rmol, madera y acero, etc\u2026 .Colocaci\u00f3n de todo tipo de papeles pintados, vin\u00edlicos, tejidos de fibra de vidrio, estampados.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"420\" height=\"389\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/camello1-1.png\" alt=\"\" class=\"wp-image-73\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/camello1-1.png 420w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/camello1-1-300x278.png 300w\" sizes=\"auto, (max-width: 420px) 100vw, 420px\" \/><figcaption class=\"wp-element-caption\"><strong>Industrial<\/strong><\/figcaption><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">Protecci\u00f3n pasiva contra Incendios, Tratamiento de solera, Pinturas para pavimentos, se\u00f1alizaciones viales, mantenimiento de maquinaria industrial \u2026<\/p>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:420px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-light-bg-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1463\" src=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-scaled.jpg\" alt=\"\" class=\"wp-image-56\" style=\"width:1166px;height:auto\" srcset=\"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-scaled.jpg 2560w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-300x171.jpg 300w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-1024x585.jpg 1024w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-768x439.jpg 768w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-1536x878.jpg 1536w, https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-content\/uploads\/2024\/06\/fondoptnuevo-2048x1170.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-cover alignfull is-light\" style=\"min-height:300px;aspect-ratio:unset;\"><span aria-hidden=\"true\" class=\"wp-block-cover__background has-nv-dark-bg-background-color has-background-dim-100 has-background-dim\"><\/span><div class=\"wp-block-cover__inner-container is-layout-flow wp-block-cover-is-layout-flow\">\n<div style=\"height:140px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h2 class=\"wp-block-heading has-text-align-center has-nv-text-dark-bg-color has-text-color\">PIDE PRESUPUESTO SIN COMPROMISO<\/h2>\n\n\n\n<p class=\"has-text-align-center has-medium-font-size wp-block-paragraph\">Puedes contactar con nosotros a trav\u00e9s de tel\u00e9fono o mail.<\/p>\n\n\n\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Direcci\u00f3n: Avda. de Lisboa, 6 C.P. 23740 And\u00fajar (Ja\u00e9n)<\/strong><\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>Tel\u00e9fonos: 647447169 &#8211; 650959568<\/strong><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p class=\"has-text-align-center wp-block-paragraph\"><strong>e-Mail: pereztorres.2007@hotmail.com<\/strong><\/p>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\"><\/div>\n<\/div>\n<\/div><\/div>\n","protected":false},"excerpt":{"rendered":"<p>Servicio Garantizado Gracias a la utilizaci\u00f3n de las mejores marcas del mercado y nuestro saber hacer podemos garantizar nuestros servicios. Particulares Atenci\u00f3n personalizada a particulares y comunidades de vecinos. Industrial Disponemos de un equipo con la m\u00e1xima experiencia en trabajos industriales.<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"neve_meta_sidebar":"","neve_meta_container":"","neve_meta_enable_content_width":"on","neve_meta_content_width":100,"neve_meta_title_alignment":"","neve_meta_author_avatar":"","neve_post_elements_order":"","neve_meta_disable_header":"","neve_meta_disable_footer":"","neve_meta_disable_title":"on","ngg_post_thumbnail":0,"footnotes":""},"class_list":["post-10","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-json\/wp\/v2\/pages\/10","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-json\/wp\/v2\/comments?post=10"}],"version-history":[{"count":15,"href":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-json\/wp\/v2\/pages\/10\/revisions"}],"predecessor-version":[{"id":127,"href":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-json\/wp\/v2\/pages\/10\/revisions\/127"}],"wp:attachment":[{"href":"https:\/\/ofiandujar.es\/pereztorrespinturas.com\/wp-json\/wp\/v2\/media?parent=10"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}